{"id":2308,"date":"2023-02-09T20:13:54","date_gmt":"2023-02-09T20:13:54","guid":{"rendered":"https:\/\/frouharlaw.com\/notre-expertise\/vol\/"},"modified":"2026-05-26T15:11:47","modified_gmt":"2026-05-26T15:11:47","slug":"vol","status":"publish","type":"page","link":"https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/","title":{"rendered":"Avocat pour vol qualifi\u00e9 \u00e0 Ottawa"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2308\" class=\"elementor elementor-2308 elementor-1273\" data-elementor-post-type=\"page\"> \t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4138d38 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"4138d38\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"> \t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div> \t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e81423\" data-id=\"6e81423\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d594a1 elementor-widget elementor-widget-html\" data-id=\"3d594a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<script type=\"application\/ld+json\">\r\n{\r\n  \"@context\": \"https:\/\/schema.org\",\r\n  \"@type\": \"LegalService\",\r\n  \"name\": \"Frouhar Law \u2014 D\u00e9fense contre le vol qualifi\u00e9 et l'extorsion \u00e0 Ottawa\",\r\n  \"url\": \"https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/\",\r\n  \"description\": \"Frouhar Law d\u00e9fend les accusations de vol qualifi\u00e9 et d'extorsion \u00e0 Ottawa et dans l'Est ontarien. Ancienne procureure de la Couronne. D\u00e9fense li\u00e9e \u00e0 l'article 343 sur le vol qualifi\u00e9, \u00e0 l'article 346 sur l'extorsion et au vol qualifi\u00e9 avec arme \u00e0 feu comportant des peines minimales obligatoires. Consultation initiale gratuite.\",\r\n  \"hasOfferCatalog\": {\r\n    \"@type\": \"OfferCatalog\",\r\n    \"name\": \"Services de d\u00e9fense contre le vol qualifi\u00e9 et l'extorsion\",\r\n    \"itemListElement\": [\r\n      {\r\n        \"@type\": \"Offer\",\r\n        \"itemOffered\": {\r\n          \"@type\": \"Service\",\r\n          \"name\": \"D\u00e9fense contre le vol qualifi\u00e9 (article 343 du Code criminel)\",\r\n          \"url\": \"https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/\"\r\n        }\r\n      },\r\n      {\r\n        \"@type\": \"Offer\",\r\n        \"itemOffered\": {\r\n          \"@type\": \"Service\",\r\n          \"name\": \"D\u00e9fense contre le vol qualifi\u00e9 avec une arme \u00e0 feu (article 344 du Code criminel)\",\r\n          \"url\": \"https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/\"\r\n        }\r\n      },\r\n      {\r\n        \"@type\": \"Offer\",\r\n        \"itemOffered\": {\r\n          \"@type\": \"Service\",\r\n          \"name\": \"D\u00e9fense contre l'extorsion (article 346 du Code criminel)\",\r\n          \"url\": \"https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/\"\r\n        }\r\n      },\r\n      {\r\n        \"@type\": \"Offer\",\r\n        \"itemOffered\": {\r\n          \"@type\": \"Service\",\r\n          \"name\": \"Requ\u00eates fond\u00e9es sur la Charte et exclusion de la preuve\",\r\n          \"url\": \"https:\/\/frouharlaw.com\/fr\/notre-expertise\/motions-et-demandes-relatives-a-la-charte\/\"\r\n        }\r\n      },\r\n      {\r\n        \"@type\": \"Offer\",\r\n        \"itemOffered\": {\r\n          \"@type\": \"Service\",\r\n          \"name\": \"D\u00e9fense contre les infractions contre les biens \u00e0 Ottawa\",\r\n          \"url\": \"https:\/\/frouharlaw.com\/fr\/notre-expertise\/infractions-contre-les-biens\/\"\r\n        }\r\n      }\r\n    ]\r\n  },\r\n  \"areaServed\": [\r\n    {\r\n      \"@type\": \"City\",\r\n      \"name\": \"Ottawa\"\r\n    },\r\n    {\r\n      \"@type\": \"AdministrativeArea\",\r\n      \"name\": \"Est ontarien\"\r\n    }\r\n  ],\r\n  \"address\": {\r\n    \"@type\": \"PostalAddress\",\r\n    \"streetAddress\": \"190 O'Connor Street, Suite 700\",\r\n    \"addressLocality\": \"Ottawa\",\r\n    \"addressRegion\": \"ON\",\r\n    \"postalCode\": \"K2P 1T6\",\r\n    \"addressCountry\": \"CA\"\r\n  },\r\n  \"geo\": {\r\n    \"@type\": \"GeoCoordinates\",\r\n    \"latitude\": 45.4179029,\r\n    \"longitude\": -75.6961238\r\n  },\r\n  \"telephone\": \"+16132382000\",\r\n  \"openingHoursSpecification\": [\r\n    {\r\n      \"@type\": \"OpeningHoursSpecification\",\r\n      \"dayOfWeek\": [\r\n        \"Monday\",\r\n        \"Tuesday\",\r\n        \"Wednesday\",\r\n        \"Thursday\",\r\n        \"Friday\"\r\n      ],\r\n      \"opens\": \"08:30\",\r\n      \"closes\": \"17:30\"\r\n    }\r\n  ],\r\n  \"contactPoint\": {\r\n    \"@type\": \"ContactPoint\",\r\n    \"telephone\": \"+16132382000\",\r\n    \"contactType\": \"service \u00e0 la client\u00e8le\",\r\n    \"areaServed\": \"CA\",\r\n    \"availableLanguage\": [\r\n      \"English\",\r\n      \"French\",\r\n      \"Spanish\"\r\n    ]\r\n  },\r\n  \"founder\": {\r\n    \"@type\": \"Person\",\r\n    \"name\": \"Mash Frouhar\",\r\n    \"jobTitle\": \"Avocate plaidante\",\r\n    \"description\": \"Ancienne procureure de la Couronne et associ\u00e9e fondatrice de Frouhar Law. Admise au Barreau en 2009. Bilingue en fran\u00e7ais et en anglais.\",\r\n    \"url\": \"https:\/\/frouharlaw.com\/fr\/notre-equipe\/mash-frouhar\/\"\r\n  },\r\n  \"employee\": [\r\n    {\r\n      \"@type\": \"Person\",\r\n      \"name\": \"Mash Frouhar\",\r\n      \"jobTitle\": \"Avocate plaidante\",\r\n      \"url\": \"https:\/\/frouharlaw.com\/fr\/notre-equipe\/mash-frouhar\/\"\r\n    },\r\n    {\r\n      \"@type\": \"Person\",\r\n      \"name\": \"Connie D'Angelo\",\r\n      \"jobTitle\": \"Avocate plaidante\",\r\n      \"url\": \"https:\/\/frouharlaw.com\/fr\/notre-equipe\/connie-dangelo\/\"\r\n    }\r\n  ],\r\n  \"memberOf\": [\r\n    {\r\n      \"@type\": \"Organization\",\r\n      \"name\": \"Association des avocats de la d\u00e9fense d'Ottawa\"\r\n    },\r\n    {\r\n      \"@type\": \"Organization\",\r\n      \"name\": \"Barreau de l'Ontario\"\r\n    },\r\n    {\r\n      \"@type\": \"Organization\",\r\n      \"name\": \"Criminal Lawyers Association\"\r\n    }\r\n  ],\r\n  \"priceRange\": \"Consultation: gratuite\"\r\n}\r\n\r\n<\/script>  \t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-b6b2304 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b6b2304\" data-element_type=\"section\" data-e-type=\"section\"> \t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d0451ec\" data-id=\"d0451ec\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-875a3f6 elementor-widget elementor-widget-heading\" data-id=\"875a3f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Avocat pour vol qualifi\u00e9 \u00e0 Ottawa <\/h1>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-3cfcfaf elementor-widget elementor-widget-n-accordion\" data-id=\"3cfcfaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\"> \t\t\t\t\t\t<details id=\"e-n-accordion-item-6390\" class=\"e-n-accordion-item\" > \t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6390\" > \t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\">  <\/div><\/span> \t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'> \t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span> \t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span> \t\t<\/span>  \t\t\t\t\t\t<\/summary> \t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-6390\" class=\"elementor-element elementor-element-213c201 e-con-full e-flex e-con e-child\" data-id=\"213c201\" data-element_type=\"container\" data-e-type=\"container\"> \t\t\t\t<div class=\"elementor-element elementor-element-0683f14 elementor-widget elementor-widget-text-editor\" data-id=\"0683f14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<h2><span style=\"color: #ffffff;\">Soutien juridique complet pour les dossiers de vol qualifi\u00e9 et d\u2019extorsion<\/span><\/h2><p><span style=\"font-weight: 400;\">Frouhar Law d\u00e9fend les accusations de vol qualifi\u00e9 que les procureurs de la Couronne portent devant le palais de justice d\u2019Ottawa et partout dans l\u2019Est de l\u2019Ontario. Ces accusations peuvent entra\u00eener des peines minimales obligatoires, une peine maximale d\u2019emprisonnement \u00e0 perp\u00e9tuit\u00e9 et des cons\u00e9quences qui touchent chaque aspect de la vie.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/details> \t\t\t\t\t<\/div> \t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-efc243d elementor-align-left elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"efc243d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\"> \t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/frouharlaw.com\/fr\/contactez-nous\/\"> \t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\"> \t\t\t\t\t\t<span class=\"elementor-button-icon\"> \t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span> \t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\"> Planifier une consultation<\/span> \t\t\t\t\t<\/span> \t\t\t\t\t<\/a> \t\t\t\t<\/div> \t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-485a233\" data-id=\"485a233\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ea9ee9 elementor-widget-mobile__width-inherit eael-gravity-form-button-custom elementor-widget elementor-widget-eael-gravity-form\" data-id=\"9ea9ee9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-gravity-form.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t<div class=\"eael-contact-form eael-gravity-form eael-contact-form-align-default\"> \t\t        <script type=\"text\/javascript\">var gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,initializeOnLoaded:function(o){gform.domLoaded&&gform.scriptsLoaded?o():!gform.domLoaded&&gform.scriptsLoaded?window.addEventListener(\"DOMContentLoaded\",o):document.addEventListener(\"gform_main_scripts_loaded\",o)},hooks:{action:{},filter:{}},addAction:function(o,n,r,t){gform.addHook(\"action\",o,n,r,t)},addFilter:function(o,n,r,t){gform.addHook(\"filter\",o,n,r,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,n){gform.removeHook(\"action\",o,n)},removeFilter:function(o,n,r){gform.removeHook(\"filter\",o,n,r)},addHook:function(o,n,r,t,i){null==gform.hooks[o][n]&&(gform.hooks[o][n]=[]);var e=gform.hooks[o][n];null==i&&(i=n+\"_\"+e.length),gform.hooks[o][n].push({tag:i,callable:r,priority:t=null==t?10:t})},doHook:function(n,o,r){var t;if(r=Array.prototype.slice.call(r,1),null!=gform.hooks[n][o]&&((o=gform.hooks[n][o]).sort(function(o,n){return o.priority-n.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==n?t.apply(null,r):r[0]=t.apply(null,r)})),\"filter\"==n)return r[0]},removeHook:function(o,n,t,i){var r;null!=gform.hooks[o][n]&&(r=(r=gform.hooks[o][n]).filter(function(o,n,r){return!!(null!=i&&i!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][n]=r)}});<\/script>                 <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_4' ><style>#gform_wrapper_4[data-form-index=\"0\"].gform-theme,[data-parent-form=\"4_0\"]{--gf-color-primary: #204ce5;--gf-color-primary-rgb: 32, 76, 229;--gf-color-primary-contrast: #fff;--gf-color-primary-contrast-rgb: 255, 255, 255;--gf-color-primary-darker: #001AB3;--gf-color-primary-lighter: #527EFF;--gf-color-secondary: #fff;--gf-color-secondary-rgb: 255, 255, 255;--gf-color-secondary-contrast: #112337;--gf-color-secondary-contrast-rgb: 17, 35, 55;--gf-color-secondary-darker: #F5F5F5;--gf-color-secondary-lighter: #FFFFFF;--gf-color-out-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-out-ctrl-light-rgb: 17, 35, 55;--gf-color-out-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-out-ctrl-light-lighter: #F5F5F5;--gf-color-out-ctrl-dark: #585e6a;--gf-color-out-ctrl-dark-rgb: 88, 94, 106;--gf-color-out-ctrl-dark-darker: #112337;--gf-color-out-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-color-in-ctrl: #fff;--gf-color-in-ctrl-rgb: 255, 255, 255;--gf-color-in-ctrl-contrast: #112337;--gf-color-in-ctrl-contrast-rgb: 17, 35, 55;--gf-color-in-ctrl-darker: #F5F5F5;--gf-color-in-ctrl-lighter: #FFFFFF;--gf-color-in-ctrl-primary: #204ce5;--gf-color-in-ctrl-primary-rgb: 32, 76, 229;--gf-color-in-ctrl-primary-contrast: #fff;--gf-color-in-ctrl-primary-contrast-rgb: 255, 255, 255;--gf-color-in-ctrl-primary-darker: #001AB3;--gf-color-in-ctrl-primary-lighter: #527EFF;--gf-color-in-ctrl-light: rgba(17, 35, 55, 0.1);--gf-color-in-ctrl-light-rgb: 17, 35, 55;--gf-color-in-ctrl-light-darker: rgba(104, 110, 119, 0.35);--gf-color-in-ctrl-light-lighter: #F5F5F5;--gf-color-in-ctrl-dark: #585e6a;--gf-color-in-ctrl-dark-rgb: 88, 94, 106;--gf-color-in-ctrl-dark-darker: #112337;--gf-color-in-ctrl-dark-lighter: rgba(17, 35, 55, 0.65);--gf-radius: 3px;--gf-font-size-secondary: 14px;--gf-font-size-tertiary: 13px;--gf-icon-ctrl-number: url(\"data:image\/svg+xml,%3Csvg width='8' height='14' viewBox='0 0 8 14' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M4 0C4.26522 5.96046e-08 4.51957 0.105357 4.70711 0.292893L7.70711 3.29289C8.09763 3.68342 8.09763 4.31658 7.70711 4.70711C7.31658 5.09763 6.68342 5.09763 6.29289 4.70711L4 2.41421L1.70711 4.70711C1.31658 5.09763 0.683417 5.09763 0.292893 4.70711C-0.0976311 4.31658 -0.097631 3.68342 0.292893 3.29289L3.29289 0.292893C3.48043 0.105357 3.73478 0 4 0ZM0.292893 9.29289C0.683417 8.90237 1.31658 8.90237 1.70711 9.29289L4 11.5858L6.29289 9.29289C6.68342 8.90237 7.31658 8.90237 7.70711 9.29289C8.09763 9.68342 8.09763 10.3166 7.70711 10.7071L4.70711 13.7071C4.31658 14.0976 3.68342 14.0976 3.29289 13.7071L0.292893 10.7071C-0.0976311 10.3166 -0.0976311 9.68342 0.292893 9.29289Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-select: url(\"data:image\/svg+xml,%3Csvg width='10' height='6' viewBox='0 0 10 6' fill='none' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cpath fill-rule='evenodd' clip-rule='evenodd' d='M0.292893 0.292893C0.683417 -0.097631 1.31658 -0.097631 1.70711 0.292893L5 3.58579L8.29289 0.292893C8.68342 -0.0976311 9.31658 -0.0976311 9.70711 0.292893C10.0976 0.683417 10.0976 1.31658 9.70711 1.70711L5.70711 5.70711C5.31658 6.09763 4.68342 6.09763 4.29289 5.70711L0.292893 1.70711C-0.0976311 1.31658 -0.0976311 0.683418 0.292893 0.292893Z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-icon-ctrl-search: url(\"data:image\/svg+xml,%3Csvg version='1.1' xmlns='http:\/\/www.w3.org\/2000\/svg' width='640' height='640'%3E%3Cpath d='M256 128c-70.692 0-128 57.308-128 128 0 70.691 57.308 128 128 128 70.691 0 128-57.309 128-128 0-70.692-57.309-128-128-128zM64 256c0-106.039 85.961-192 192-192s192 85.961 192 192c0 41.466-13.146 79.863-35.498 111.248l154.125 154.125c12.496 12.496 12.496 32.758 0 45.254s-32.758 12.496-45.254 0L367.248 412.502C335.862 434.854 297.467 448 256 448c-106.039 0-192-85.962-192-192z' fill='rgba(17, 35, 55, 0.65)'\/%3E%3C\/svg%3E\");--gf-label-space-y-secondary: var(--gf-label-space-y-md-secondary);--gf-ctrl-border-color: #686e77;--gf-ctrl-size: var(--gf-ctrl-size-md);--gf-ctrl-label-color-primary: #112337;--gf-ctrl-label-color-secondary: #112337;--gf-ctrl-choice-size: var(--gf-ctrl-choice-size-md);--gf-ctrl-checkbox-check-size: var(--gf-ctrl-checkbox-check-size-md);--gf-ctrl-radio-check-size: var(--gf-ctrl-radio-check-size-md);--gf-ctrl-btn-font-size: var(--gf-ctrl-btn-font-size-md);--gf-ctrl-btn-padding-x: var(--gf-ctrl-btn-padding-x-md);--gf-ctrl-btn-size: var(--gf-ctrl-btn-size-md);--gf-ctrl-btn-border-color-secondary: #686e77;--gf-ctrl-file-btn-bg-color-hover: #EBEBEB;--gf-field-pg-steps-number-color: rgba(17, 35, 55, 0.8);}<\/style><div id='gf_4' class='gform_anchor' tabindex='-1'><\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_4' id='gform_4'  action='\/fr\/wp-json\/wp\/v2\/pages\/2308#gf_4' data-formid='4' novalidate>                         <div class='gform-body gform_body'><div id='gform_fields_4' class='gform_fields top_label form_sublabel_below description_below validation_below'><fieldset id=\"field_4_1\" class=\"gfield gfield--type-name gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  data-js-reload=\"field_4_1\" ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Name<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(N\u00e9cessaire)<\/span><\/span><\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_4_1'>                                                          <span id='input_4_1_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >                                                     <input type='text' name='input_1.3' id='input_4_1_3' value=''   aria-required='true'     \/>                                                     <label for='input_4_1_3' class='gform-field-label gform-field-label--type-sub'>Pr\u00e9nom<\/label>                                                 <\/span>                                                          <span id='input_4_1_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >                                                     <input type='text' name='input_1.6' id='input_4_1_6' value=''   aria-required='true'     \/>                                                     <label for='input_4_1_6' class='gform-field-label gform-field-label--type-sub'>Nom<\/label>                                                 <\/span>                                                      <\/div><\/fieldset><div id=\"field_4_2\" class=\"gfield gfield--type-phone gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  data-js-reload=\"field_4_2\" ><label class='gfield_label gform-field-label' for='input_4_2'>Phone<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(N\u00e9cessaire)<\/span><\/span><\/label><div class='ginput_container ginput_container_phone'><input name='input_2' id='input_4_2' type='tel' value='' class='large'   aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_4_3\" class=\"gfield gfield--type-email gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  data-js-reload=\"field_4_3\" ><label class='gfield_label gform-field-label' for='input_4_3'>Email<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(N\u00e9cessaire)<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>                             <input name='input_3' id='input_4_3' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>                         <\/div><\/div><div id=\"field_4_4\" class=\"gfield gfield--type-textarea gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  data-js-reload=\"field_4_4\" ><label class='gfield_label gform-field-label' for='input_4_4'>Message<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(N\u00e9cessaire)<\/span><\/span><\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_4' id='input_4_4' class='textarea large'     aria-required=\"true\" aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><div id=\"field_4_5\" class=\"gfield gfield--type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  data-js-reload=\"field_4_5\" ><div class='ginput_container ginput_container_text'><input name='input_5' id='input_4_5' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_4_10\" class=\"gfield gfield--type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  data-js-reload=\"field_4_10\" ><div class='ginput_container ginput_container_text'><input name='input_10' id='input_4_10' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='https:\/\/frouharlaw.com\/fr\/wp-json\/wp\/v2\/pages\/2308' \/><\/div><\/div><div id=\"field_4_6\" class=\"gfield gfield--type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  data-js-reload=\"field_4_6\" ><div class='ginput_container ginput_container_text'><input name='input_6' id='input_4_6' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='https:\/\/frouharlaw.com\/fr\/wp-json\/wp\/v2\/pages\/2266' \/><\/div><\/div><div id=\"field_4_7\" class=\"gfield gfield--type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  data-js-reload=\"field_4_7\" ><div class='ginput_container ginput_container_text'><input name='input_7' id='input_4_7' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='216.73.217.73' \/><\/div><\/div><div id=\"field_4_8\" class=\"gfield gfield--type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  data-js-reload=\"field_4_8\" ><div class='ginput_container ginput_container_text'><input name='input_8' id='input_4_8' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_4_9\" class=\"gfield gfield--type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  data-js-reload=\"field_4_9\" ><div class='ginput_container ginput_container_text'><input name='input_9' id='input_4_9' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_4_11\" class=\"gfield gfield--type-captcha gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  data-js-reload=\"field_4_11\" ><label class='gfield_label gform-field-label' for='input_4_11'>CAPTCHA<\/label><div id='input_4_11' class='ginput_container ginput_recaptcha' data-sitekey='6LclV6QpAAAAAMdmk0dggFpMUNTkRLX8SOtyqAkD'  data-theme='light' data-tabindex='0'  data-badge=''><\/div><\/div><\/div><\/div>         <div class='gform_footer top_label'> <input type='submit' id='gform_submit_button_4' class='gform_button button' value='Submit'  onclick='if(window[\"gf_submitting_4\"]){return false;}  if( !jQuery(\"#gform_4\")[0].checkValidity || jQuery(\"#gform_4\")[0].checkValidity()){window[\"gf_submitting_4\"]=true;}  ' onkeypress='if( event.keyCode == 13 ){ if(window[\"gf_submitting_4\"]){return false;} if( !jQuery(\"#gform_4\")[0].checkValidity || jQuery(\"#gform_4\")[0].checkValidity()){window[\"gf_submitting_4\"]=true;}  jQuery(\"#gform_4\").trigger(\"submit\",[true]); }' \/> <input type='hidden' name='gform_ajax' value='form_id=4&amp;title=&amp;description=&amp;tabindex=0&amp;theme=gravity-theme' \/>             <input type='hidden' class='gform_hidden' name='is_submit_4' value='1' \/>             <input type='hidden' class='gform_hidden' name='gform_submit' value='4' \/>                          <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>             <input type='hidden' class='gform_hidden' name='state_4' value='WyJbXSIsImQ0NzA5ZmFlM2JkMWE5ZTVmM2EzY2NkNjMzNWQxMWY3Il0=' \/>             <input type='hidden' class='gform_hidden' name='gform_target_page_number_4' id='gform_target_page_number_4' value='0' \/>             <input type='hidden' class='gform_hidden' name='gform_source_page_number_4' id='gform_source_page_number_4' value='1' \/>             <input type='hidden' name='gform_field_values' value='' \/>                      <\/div>                         <\/form>                         <\/div> \t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_4' id='gform_ajax_frame_4' title='Cette iframe contient la logique n\u00e9cessaire pour manipuler Gravity Forms avec Ajax.'><\/iframe> \t\t                <script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 4, 'https:\/\/frouharlaw.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_4').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_4');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_4').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_4').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_4').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_4').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_4').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_4').val();gformInitSpinner( 4, 'https:\/\/frouharlaw.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [4, current_page]);window['gf_submitting_4'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_4').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_4').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [4]);window['gf_submitting_4'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_4').text());}else{jQuery('#gform_4').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"4\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);                if (event && event.defaultPrevented) {                return;         }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_4\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_4\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_4\" );        let postRenderFired = false;                function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            jQuery( document ).trigger( 'gform_post_render', [4, current_page] );            gform.utils.trigger( { event: 'gform\/postRender', native: false, data: { formId: 4, currentPage: current_page } } );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script> \t\t\t<\/div>              <script type=\"text\/javascript\">\n                var gf_global = {\"gf_currency_config\":{\"name\":\"Dollar canadien\",\"symbol_left\":\"$\",\"symbol_right\":\"CAD\",\"symbol_padding\":\" \",\"thousand_separator\":\",\",\"decimal_separator\":\".\",\"decimals\":2,\"code\":\"CAD\"},\"base_url\":\"https:\\\/\\\/frouharlaw.com\\\/wp-content\\\/plugins\\\/gravityforms\",\"number_formats\":[],\"spinnerUrl\":\"https:\\\/\\\/frouharlaw.com\\\/wp-content\\\/plugins\\\/gravityforms\\\/images\\\/spinner.svg\",\"version_hash\":\"7a957dc0a01a60d015245f5fb9c8f21d\",\"strings\":{\"newRowAdded\":\"Nouvelle ligne ajout\\u00e9e.\",\"rowRemoved\":\"Rang\\u00e9e supprim\\u00e9e\",\"formSaved\":\"Le formulaire a \\u00e9t\\u00e9 enregistr\\u00e9. Le contenu contient le lien pour retourner et terminer le formulaire.\"}};\t\t\t\tvar gf_vars = {\"active\":\"Actif\",\"inactive\":\"Inactif\",\"save\":\"Enregistrer\",\"update\":\"Mettre \\u00e0 jour\",\"previousLabel\":\"Pr\\u00e9c\\u00e9dent\",\"selectFormat\":\"S\\u00e9lectionnez un format\",\"column\":\"Colonne\",\"editToViewAll\":\"5 \\u00e9l\\u00e9ments sur %d affich\\u00e9s. Modifiez le champ pour tout afficher.\",\"selectAll\":\"Tout s\\u00e9lectionner\",\"enterValue\":\"Saisir une valeur\",\"formTitle\":\"Formulaire sans titre\",\"formDescription\":\"N\\u2019h\\u00e9sitez pas \\u00e0 communiquer avec nous ! Veuillez remplir ce formulaire et nous vous r\\u00e9pondrons sous peu.\",\"formConfirmationMessage\":\"Merci de nous avoir contact\\u00e9s ! Nous vous r\\u00e9pondrons sous peu.\",\"buttonText\":\"Envoyer\",\"buttonDescription\":\"Le bouton d\\u2019envoi de ce formulaire\",\"loading\":\"Chargement...\",\"thisFieldIf\":\"ce champ si\",\"thisSectionIf\":\"cette section si\",\"thisPage\":\"cette page si\",\"thisFormButton\":\"ce bouton de formulaire si\",\"show\":\"Afficher\",\"hide\":\"Masquer\",\"enable\":\"Activer\",\"disable\":\"D\\u00e9sactiver\",\"enabled\":\"Activ\\u00e9\",\"disabled\":\"D\\u00e9sactiv\\u00e9\",\"configure\":\"Configurer\",\"conditional_logic_text\":\"Logique conditionnelle\",\"conditional_logic_desc\":\"La logique conditionnelle vous permet de modifier ce que l\\u2019utilisateur ou l\\u2019utilisatrice voit en fonction des champs s\\u00e9lectionn\\u00e9s.\",\"conditional_logic_a11y\":\"L\\u2019ajout d\\u2018une logique conditionnelle au bouton d\\u2019envoi du formulaire peut entra\\u00eener des probl\\u00e8mes d\\u2019utilisation pour certaines personnes et avoir un impact n\\u00e9gatif sur l\\u2019accessibilit\\u00e9 de votre formulaire. Pour en savoir plus sur la logique conditionnelle des boutons, consultez notre <a href=\\\"https:\\\/\\\/docs.gravityforms.com\\\/field-accessibility-warning\\\/\\\" target=\\\"_blank\\\" rel=\\\"noopener\\\">documentation<\\\/a>.\",\"page\":\"Page\",\"next_button\":\"Bouton suivant\",\"button\":\"Bouton d\\u2019envoi\",\"all\":\"Tous\",\"any\":\"Certains\",\"ofTheFollowingMatch\":\"l(d)es crit\\u00e8res suivants correspondent :\",\"is\":\"est\",\"isNot\":\"n\\u2019est pas\",\"greaterThan\":\"plus grand que\",\"lessThan\":\"plus petit que\",\"contains\":\"contient\",\"startsWith\":\"commence avec\",\"endsWith\":\"finit avec\",\"emptyChoice\":\"Vide (aucun choix s\\u00e9lectionn\\u00e9)\",\"alertLegacyMode\":\"Ce formulaire utilise d\\u2018anciennes balises et ne prend pas en charge le redimensionnement des champs dans l\\u2019\\u00e9diteur. Veuillez d\\u00e9sactiver l\\u2019ancien balisage dans les r\\u00e9glages du formulaire pour activer le redimensionnement en temps r\\u00e9el.\",\"thisConfirmation\":\"Utiliser cette confirmation si\",\"thisNotification\":\"Envoyer cette notification si\",\"confirmationSave\":\"Enregistrer\",\"confirmationSaving\":\"Enregistrement...\",\"confirmationAreYouSure\":\"Voulez-vous vraiment annuler ces modifications ?\",\"confirmationIssueSaving\":\"Une erreur s\\u2019est produite lors de l\\u2019enregistrement de la confirmation.\",\"confirmationConfirmDelete\":\"Voulez-vous vraiment supprimer cette confirmation ?\",\"confirmationIssueDeleting\":\"Une erreur s\\u2019est produite lors de la suppression de la confirmation.\",\"confirmationConfirmDiscard\":\"Les changements apport\\u00e9s \\u00e0 cette confirmation n\\u2019ont pas \\u00e9t\\u00e9 enregistr\\u00e9s. Voulez-vous vraiment annuler ces changements ?\",\"confirmationDefaultName\":\"Confirmation sans titre\",\"confirmationDefaultMessage\":\"Merci de nous avoir contact\\u00e9s ! Nous vous r\\u00e9pondrons sous peu.\",\"confirmationInvalidPageSelection\":\"Veuillez s\\u00e9lectionner une page.\",\"confirmationInvalidRedirect\":\"Veuillez saisir une URL.\",\"confirmationInvalidName\":\"Veuillez saisir un nom pour la confirmation.\",\"confirmationDeleteField\":\"Avertissement ! La suppression de ce champ entra\\u00eenera la suppression de toutes les donn\\u00e9es qui y sont associ\\u00e9es. \\u00ab OK \\u00bb pour supprimer, \\u00ab Annuler \\u00bb pour arr\\u00eater.\",\"confirmationDeleteDisplayField\":\"Avertissement\\u00a0! Vous allez supprimer ce champ. \\u00ab\\u00a0Annuler\\u00a0\\u00bb pour arr\\u00eater. \\u00ab\\u00a0OK\\u00a0\\u00bb pour supprimer.\",\"conditionalLogicDependency\":\"Avertissement ! Ce formulaire contient une logique conditionnelle d\\u00e9pendant de ce champ. La suppression de ce champ d\\u00e9sactivera ces r\\u00e8gles de logique conditionnelle et supprimera aussi toutes les entr\\u00e9es de donn\\u00e9es associ\\u00e9es avec ce champ. \\u00ab\\u00a0OK\\u00a0\\u00bb pour supprimer, \\u00ab\\u00a0Annuler\\u00a0\\u00bb pour abandonner.\",\"conditionalLogicDependencyChoice\":\"Ce formulaire comporte des logiques conditionnelles qui d\\u00e9pendent de ce choix. Voulez-vous malgr\\u00e9 tout supprimer ce choix ? \\u00ab\\u00a0OK\\u00a0\\u00bb pour supprimer, \\u00ab\\u00a0Annuler\\u00a0\\u00bb pour abandonner.\",\"conditionalLogicDependencyChoiceEdit\":\"Ce formulaire comporte des logiques conditionnelles qui d\\u00e9pendent de ce choix. Voulez-vous malgr\\u00e9 tout modifier ce choix ? \\u00ab\\u00a0OK\\u00a0\\u00bb pour supprimer, \\u00ab\\u00a0Annuler\\u00a0\\u00bb pour abandonner.\",\"conditionalLogicDependencyAdminOnly\":\"Ce formulaire comporte des logiques conditionnelles qui d\\u00e9pendent de ce champ. Voulez-vous malgr\\u00e9 tout supprimer ce champ ? \\u00ab\\u00a0OK\\u00a0\\u00bb pour supprimer, \\u00ab\\u00a0Annuler\\u00a0\\u00bb pour abandonner.\",\"mergeTagsText\":\"Ins\\u00e9rer des balises de fusion\",\"baseUrl\":\"https:\\\/\\\/frouharlaw.com\\\/wp-content\\\/plugins\\\/gravityforms\",\"gf_currency_config\":{\"name\":\"Dollar canadien\",\"symbol_left\":\"$\",\"symbol_right\":\"CAD\",\"symbol_padding\":\" \",\"thousand_separator\":\",\",\"decimal_separator\":\".\",\"decimals\":2,\"code\":\"CAD\"},\"otherChoiceValue\":\"Autre\",\"isFormTrash\":false,\"currentlyAddingField\":false,\"visibilityOptions\":[{\"label\":\"Visible\",\"value\":\"visible\",\"description\":\"Option par d\\u00e9faut. Ce champ est visible quand le formulaire est affich\\u00e9.\"},{\"label\":\"Masqu\\u00e9\",\"value\":\"hidden\",\"description\":\"Ce champ est masqu\\u00e9 quand le formulaire est affich\\u00e9. Utile si vous avez besoin de la fonctionnalit\\u00e9 de ce champ mais que vous ne voulez pas que l\\u2019utilisateur ou l\\u2019utilisatrice puisse le voir.\"},{\"label\":\"Administration\",\"value\":\"administrative\",\"description\":\"Ce champ est visible uniquement pendant l\\u2019administration des entr\\u00e9es envoy\\u00e9es. Ce champ n\\u2019est pas visible ou fonctionnel lorsque le formulaire est vu.\"}],\"addFieldFilter\":\"Ajouter une condition\",\"removeFieldFilter\":\"Retirer une condition\",\"filterAndAny\":\"{0} des crit\\u00e8res suivants correspondent\\u00a0:\",\"customChoices\":\"Choix personnalis\\u00e9s\",\"predefinedChoices\":\"Choix pr\\u00e9d\\u00e9finis\",\"fieldLabelAriaLabel\":\"{field_label} - {field_type}, aller aux r\\u00e9glages de ce fichier\",\"nameFieldDefaultPrefixes\":[{\"text\":\"Dr\",\"value\":\"Dr\"},{\"text\":\"M.\",\"value\":\"M.\"},{\"text\":\"MM.\",\"value\":\"MM.\"},{\"text\":\"Mlle\",\"value\":\"Mlle\"},{\"text\":\"Mme\",\"value\":\"Mme\"},{\"text\":\"Mmes\",\"value\":\"Mmes\"},{\"text\":\"Prof\",\"value\":\"Prof\"},{\"text\":\"Rev.\",\"value\":\"Rev.\"}]};\t\t\t<\/script>             \t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-9660fb5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9660fb5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"> \t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68b5b60\" data-id=\"68b5b60\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e56ca5 elementor-widget elementor-widget-heading\" data-id=\"6e56ca5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Communiquer avec un avocat en d\u00e9fense contre le vol qualifi\u00e9 pr\u00e8s de chez moi <\/h3>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-d465d0a elementor-widget elementor-widget-heading\" data-id=\"d465d0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\t\u2706 613.238.2000<\/h3>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-eaa7e8e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"eaa7e8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\"> \t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/frouharlaw.com\/fr\/contact\/\"> \t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\"> \t\t\t\t\t\t<span class=\"elementor-button-icon\"> \t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span> \t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Planifier une consultation<\/span> \t\t\t\t\t<\/span> \t\t\t\t\t<\/a> \t\t\t\t<\/div> \t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-79f2dd5e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79f2dd5e\" data-element_type=\"section\" data-e-type=\"section\"> \t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c551671\" data-id=\"3c551671\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-1785befb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1785befb\" data-element_type=\"section\" data-e-type=\"section\"> \t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-377efec\" data-id=\"377efec\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-3efd75bd elementor-widget elementor-widget-heading\" data-id=\"3efd75bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Nos Competences<\/span>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-703a2906 elementor-widget elementor-widget-heading\" data-id=\"703a2906\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vous faites face \u00e0 des accusations de vol qualifi\u00e9 ou d\u2019extorsion \u00e0 Ottawa ? <\/h2>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4af0c0a1\" data-id=\"4af0c0a1\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdf742 elementor-widget elementor-widget-text-editor\" data-id=\"cdf742\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Si vous \u00eates accus\u00e9 de vol qualifi\u00e9 \u00e0 Ottawa, vous faites face \u00e0 une infraction strictement punissable par mise en accusation, et votre libert\u00e9, votre casier judiciaire et votre avenir sont en jeu. \u00c0 titre de cabinet d\u2019avocats criminalistes que les clients d\u2019Ottawa retiennent pour des <\/span><a href=\"https:\/\/frouharlaw.com\/fr\/notre-expertise\/infractions-contre-les-biens\/\"><span style=\"font-weight: 400;\">infractions contre les biens \u00e0 Ottawa<\/span><\/a><span style=\"font-weight: 400;\">, Frouhar Law d\u00e9fend ces accusations avec la strat\u00e9gie et la plaidoirie qu\u2019elles exigent.<\/span><\/p><h4>Une audience de mise en libert\u00e9 sous caution est la premi\u00e8re \u00e9tape judiciaire apr\u00e8s une arrestation. D\u00e9couvrez comment fonctionne <a href=\"https:\/\/frouharlaw.com\/fr\/blog\/mise-en-liberte-sous-caution-canada\/\">la mise en libert\u00e9 sous caution au Canada<\/a>.<\/h4>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-f4a92fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f4a92fc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"> \t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b740493\" data-id=\"b740493\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ab3816 elementor-widget elementor-widget-heading\" data-id=\"0ab3816\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pourquoi choisir Frouhar Law pour une d\u00e9fense l\u00e9gale contre le vol qualifi\u00e9?<\/h2>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-d05f30e elementor-widget elementor-widget-heading\" data-id=\"d05f30e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"> Les d\u00e9cisions prises dans les premi\u00e8res heures suivant une arrestation pour vol qualifi\u00e9 ou extorsion peuvent influencer votre position \u00e0 l\u2019enqu\u00eate sur mise en libert\u00e9 sous caution, votre strat\u00e9gie de d\u00e9fense et la solidit\u00e9 du dossier de la Couronne.<\/h4>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-2c866fb elementor-widget elementor-widget-heading\" data-id=\"2c866fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"> Parlez \u00e0 un avocat en d\u00e9fense de vol qualifi\u00e9 <\/h5>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-0189f95 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"0189f95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\"> \t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/frouharlaw.com\/fr\/contactez-nous\/\"> \t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\"> \t\t\t\t\t\t<span class=\"elementor-button-icon\"> \t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span> \t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Planifier une consultation<\/span> \t\t\t\t\t<\/span> \t\t\t\t\t<\/a> \t\t\t\t<\/div> \t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1cb73f0\" data-id=\"1cb73f0\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-45d9961 elementor-widget elementor-widget-text-editor\" data-id=\"45d9961\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<p><b>Frouhar Law concentre sa pratique sur la d\u00e9fense p\u00e9nale. La d\u00e9fense contre les accusations de vol qualifi\u00e9 et d\u2019extorsion exige des avocats qui comprennent comment les procureurs de la Couronne b\u00e2tissent ces dossiers.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-d9e0959 elementor-widget elementor-widget-heading\" data-id=\"d9e0959\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Une ancienne procureure de la Couronne \u00e0 vos c\u00f4t\u00e9s <\/h3>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-12deab0 elementor-widget elementor-widget-text-editor\" data-id=\"12deab0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/frouharlaw.com\/fr\/notre-equipe\/mash-frouhar\/\"><span style=\"font-weight: 400;\">Mash Frouhar<\/span><\/a><span style=\"font-weight: 400;\">, ancienne procureure de la Couronne, sait quelles preuves la poursuite priorise et o\u00f9 ses th\u00e9ories peuvent \u00eatre vuln\u00e9rables. Nos avocats comparaissent au palais de justice d\u2019Ottawa ainsi que partout dans l\u2019Est de l\u2019Ontario.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-56458c1 elementor-widget elementor-widget-heading\" data-id=\"56458c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">D\u00e9fense bilingue en anglais et en fran\u00e7ais <\/h3>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-b54d92e elementor-widget elementor-widget-text-editor\" data-id=\"b54d92e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">En tant qu\u2019avocate bilingue, Frouhar Law d\u00e9fend ses clients en anglais et en fran\u00e7ais, devant les tribunaux, pendant l\u2019examen de la divulgation et dans chaque interaction avec le client. Aucun client ne devrait faire face \u00e0 une accusation de vol qualifi\u00e9 sans comprendre pleinement chaque \u00e9tape.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-dfa262f elementor-widget elementor-widget-heading\" data-id=\"dfa262f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Disponible 24 heures sur 24, y compris le soir de votre arrestation <\/h3>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-f6d9e96 elementor-widget elementor-widget-text-editor\" data-id=\"f6d9e96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Notre disponibilit\u00e9 24 heures sur 24 signifie qu\u2019un avocat de la d\u00e9fense peut \u00eatre joint avant tout interrogatoire policier. Le droit de retenir les services d\u2019un avocat sans d\u00e9lai est prot\u00e9g\u00e9 par la Charte canadienne des droits et libert\u00e9s. Appelez avant de dire quoi que ce soit.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-b92b685 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b92b685\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"> \t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-622718d\" data-id=\"622718d\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-957ce81 elementor-widget elementor-widget-heading\" data-id=\"957ce81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rencontrez notre \u00e9quipe de d\u00e9fense contre le vol qualifi\u00e9 \u00e0 Ottawa<\/h2>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-29913bf elementor-widget elementor-widget-heading\" data-id=\"29913bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Rencontrez notre \u00e9quipe<\/h3>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-0ad0573 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ad0573\" data-element_type=\"section\" data-e-type=\"section\"> \t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-55fa472\" data-id=\"55fa472\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5e7417 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"e5e7417\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/frouharlaw.com\/our-team\/mash-frouhar\/\"> \t\t\t\t\t\t\t<div class=\"elementor-cta__content\"> \t\t\t\t \t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\"> \t\t\t\t\t\tMash Frouhar\t\t\t\t\t<\/h2> \t\t\t\t \t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\"> \t\t\t\t\t\tBarrister &amp; Solicitor\t\t\t\t\t<\/div> \t\t\t\t \t\t\t\t\t\t\t<\/div> \t\t\t\t\t\t<\/a> \t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e2a9f16\" data-id=\"e2a9f16\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0cc80c elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"d0cc80c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/frouharlaw.com\/our-team\/connie-dangelo\/\"> \t\t\t\t\t\t\t<div class=\"elementor-cta__content\"> \t\t\t\t \t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\"> \t\t\t\t\t\tConnie D\u2019Angelo\t\t\t\t\t<\/h2> \t\t\t\t \t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\"> \t\t\t\t\t\tBarrister &amp; Solicitor\t\t\t\t\t<\/div> \t\t\t\t \t\t\t\t\t\t\t<\/div> \t\t\t\t\t\t<\/a> \t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-17072c7\" data-id=\"17072c7\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-78c6d32 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"78c6d32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/frouharlaw.com\/?page_id=384\"> \t\t\t\t\t\t\t<div class=\"elementor-cta__content\"> \t\t\t\t \t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\"> \t\t\t\t\t\tBenjamin Steinberg-Zwirek\t\t\t\t\t<\/h2> \t\t\t\t \t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\"> \t\t\t\t\t\tBarrister &amp; Solicitor\t\t\t\t\t<\/div> \t\t\t\t \t\t\t\t\t\t\t<\/div> \t\t\t\t\t\t<\/a> \t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<div class=\"elementor-element elementor-element-5aa63df elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5aa63df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\"> \t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/frouharlaw.com\/fr\/notre-equipe\/\"> \t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\"> \t\t\t\t\t\t<span class=\"elementor-button-icon\"> \t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span> \t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\"> Rencontrer toute l\u2019\u00e9quipe<\/span> \t\t\t\t\t<\/span> \t\t\t\t\t<\/a> \t\t\t\t<\/div> \t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-074fdb8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"074fdb8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"> \t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3e4ea68\" data-id=\"3e4ea68\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae02b81 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ae02b81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les accusations de vol qualifi\u00e9 en vertu du Code criminel <\/h2>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-b7f5916 elementor-widget elementor-widget-text-editor\" data-id=\"b7f5916\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Le vol qualifi\u00e9 est d\u00e9fini dans le <\/span><a href=\"https:\/\/laws-lois.justice.gc.ca\/fra\/lois\/c-46\/\"><span style=\"font-weight: 400;\">Code criminel du Canada<\/span><\/a><span style=\"font-weight: 400;\"> comme un vol accompagn\u00e9 de violence, de menaces de violence ou de l\u2019utilisation d\u2019une arme. Il ne s\u2019agit pas simplement d\u2019un vol. La force ou les menaces \u00e9l\u00e8vent l\u2019accusation au niveau du vol qualifi\u00e9 et augmentent consid\u00e9rablement les peines possibles.<\/span><\/p><p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Des strat\u00e9gies efficaces de d\u00e9fense contre le vol qualifi\u00e9 commencent par une compr\u00e9hension pr\u00e9cise de ce que la Couronne doit prouver.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-584bea2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"584bea2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"> \t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7a2a03f\" data-id=\"7a2a03f\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c9375f elementor-widget elementor-widget-heading\" data-id=\"1c9375f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/laws-lois.justice.gc.ca\/fra\/lois\/c-46\/section-343.html\">Ce qui constitue un vol qualifi\u00e9 au Canada (article 343) <\/a><\/h3>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-14ade0a\" data-id=\"14ade0a\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-3543a58 elementor-widget elementor-widget-text-editor\" data-id=\"3543a58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">En vertu de <\/span><a href=\"https:\/\/laws-lois.justice.gc.ca\/fra\/lois\/c-46\/section-343.html\"><span style=\"font-weight: 400;\">l\u2019article 343 du Code criminel<\/span><\/a><span style=\"font-weight: 400;\">, commet un vol qualifi\u00e9 quiconque :<\/span><\/p><ol><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">vole et emploie la violence ou des menaces de violence pour extorquer ce qui est vol\u00e9 ou emp\u00eacher la r\u00e9sistance;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">vole et, imm\u00e9diatement avant, pendant ou apr\u00e8s le vol, blesse, bat ou emploie la violence personnelle;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">agresse une personne avec l\u2019intention de la voler;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">vole alors qu\u2019il est arm\u00e9 d\u2019une arme offensive ou d\u2019une imitation d\u2019arme.<\/span><\/li><\/ol><p><span style=\"font-weight: 400;\">Le vol qualifi\u00e9 est une infraction strictement punissable par mise en accusation. Le vol lui-m\u00eame est d\u00e9fini aux <\/span><a href=\"https:\/\/laws-lois.justice.gc.ca\/fra\/lois\/c-46\/section-322.html\"><span style=\"font-weight: 400;\">articles 322<\/span><\/a><span style=\"font-weight: 400;\"> et <\/span><a href=\"https:\/\/laws-lois.justice.gc.ca\/fra\/lois\/c-46\/section-334.html\"><span style=\"font-weight: 400;\">334<\/span><\/a><span style=\"font-weight: 400;\"> du Code criminel, mais le vol \u00e0 main arm\u00e9e ou le vol qualifi\u00e9 avec une arme constitue souvent l\u2019\u00e9l\u00e9ment aggravant sur lequel les procureurs s\u2019appuient. L\u2019accusation peut couvrir des situations allant <\/span><a href=\"https:\/\/frouharlaw.com\/fr\/notre-expertise\/infractions-contre-les-biens\/introduction-par-effraction\/\"><span style=\"font-weight: 400;\">d\u2019accusations d\u2019introduction par effraction<\/span><\/a><span style=\"font-weight: 400;\"> impliquant une force ill\u00e9gale \u00e0 des <\/span><a href=\"https:\/\/frouharlaw.com\/fr\/notre-expertise\/infractions-contre-les-biens\/home-invasions\/\"><span style=\"font-weight: 400;\">accusations d\u2019invasion de domicile<\/span><\/a><span style=\"font-weight: 400;\"> o\u00f9 l\u2019accus\u00e9 aurait menac\u00e9 des occupants alors qu\u2019il \u00e9tait arm\u00e9.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-a7c4a44 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a7c4a44\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"> \t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-32a2d31\" data-id=\"32a2d31\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb5d00e elementor-widget elementor-widget-heading\" data-id=\"fb5d00e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Peines minimales obligatoires pour vol qualifi\u00e9 avec une arme \u00e0 feu<\/h3>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d779699\" data-id=\"d779699\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd4dabc elementor-widget elementor-widget-text-editor\" data-id=\"bd4dabc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/laws-lois.justice.gc.ca\/fra\/lois\/c-46\/section-344.html\"><span style=\"font-weight: 400;\">L\u2019article 344 du Code criminel<\/span><\/a><span style=\"font-weight: 400;\"> pr\u00e9voit les peines applicables au vol qualifi\u00e9 avec une arme \u00e0 feu et les peines minimales obligatoires. Un vol qualifi\u00e9 commis avec une arme \u00e0 feu \u00e0 autorisation restreinte ou prohib\u00e9e entra\u00eene une peine minimale obligatoire de 5 ans d\u2019emprisonnement. Un vol qualifi\u00e9 commis avec toute autre arme \u00e0 feu entra\u00eene une peine minimale de 4 ans. La peine maximale pour toute forme de vol qualifi\u00e9 est l\u2019emprisonnement \u00e0 perp\u00e9tuit\u00e9. Lorsque des <\/span><a href=\"https:\/\/frouharlaw.com\/fr\/notre-expertise\/armes-et-armes-a-feu\/possession-darmes-a-feu-prohibees-a-autorisation-restreinte\/\"><span style=\"font-weight: 400;\">accusations li\u00e9es aux armes<\/span><\/a><span style=\"font-weight: 400;\"> \u00e0 feu sont port\u00e9es en plus d\u2019une accusation de vol qualifi\u00e9, l\u2019exposition aux peines minimales peut s\u2019alourdir.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-1c0a89c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c0a89c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"> \t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-671a91c\" data-id=\"671a91c\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-41fc2df elementor-widget elementor-widget-heading\" data-id=\"41fc2df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vol qualifi\u00e9 et organisations criminelles <\/h3>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-da94a20\" data-id=\"da94a20\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd81f56 elementor-widget elementor-widget-text-editor\" data-id=\"dd81f56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Lorsque la Couronne prouve qu\u2019un vol qualifi\u00e9 a \u00e9t\u00e9 commis au profit, sous la direction ou en association avec une organisation criminelle, la peine minimale de 5 ans s\u2019applique m\u00eame sans arme \u00e0 feu. Cette disposition vise les vols qualifi\u00e9s li\u00e9s aux gangs et exige que la poursuite prouve \u00e0 la fois le vol qualifi\u00e9 et le lien organisationnel de l\u2019accus\u00e9 hors de tout doute raisonnable.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-918af0e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"918af0e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"> \t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9dc68c6\" data-id=\"9dc68c6\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-c64bd86 elementor-widget elementor-widget-heading\" data-id=\"c64bd86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Les accusations d\u2019extorsion en vertu du Code criminel <\/h2>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-7b5d324 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"7b5d324\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\"> \t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/frouharlaw.com\/fr\/contactez-nous\/\"> \t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\"> \t\t\t\t\t\t<span class=\"elementor-button-icon\"> \t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span> \t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Planifier une consultation<\/span> \t\t\t\t\t<\/span> \t\t\t\t\t<\/a> \t\t\t\t<\/div> \t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fd2a3fb\" data-id=\"fd2a3fb\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-574a9b9 elementor-widget elementor-widget-heading\" data-id=\"574a9b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/laws-lois.justice.gc.ca\/fra\/lois\/c-46\/section-346.html\">Ce qui constitue de l\u2019extorsion (article 346) <\/a><\/h3>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-f505f74 elementor-widget elementor-widget-text-editor\" data-id=\"f505f74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">En vertu de <\/span><a href=\"https:\/\/laws-lois.justice.gc.ca\/fra\/lois\/c-46\/section-346.html\"><span style=\"font-weight: 400;\">l\u2019article 346 du Code criminel<\/span><\/a><span style=\"font-weight: 400;\">, une personne commet une extorsion lorsqu\u2019elle, sans justification raisonnable, induit ou tente d\u2019induire une personne, par menaces, accusations, violences ou autres moyens intimidants, \u00e0 faire quelque chose. Contrairement au vol qualifi\u00e9, o\u00f9 la force intervient pendant le vol, l\u2019extorsion vise les menaces utilis\u00e9es pour contraindre une action, qu\u2019un vol soit impliqu\u00e9 ou non. Les exemples courants incluent le fait de menacer de divulguer de l\u2019information \u00e0 moins d\u2019\u00eatre pay\u00e9 ou d\u2019exiger de l\u2019argent sous menace de pr\u00e9judice.<\/span><\/p><p><span style=\"font-weight: 400;\">L\u2019extorsion chevauche souvent des accusations <\/span><a href=\"https:\/\/frouharlaw.com\/fr\/notre-expertise\/crimes-du-systeme-judiciaire\/entrave-a-la-justice-et-parjure\/\"><span style=\"font-weight: 400;\">d\u2019entrave \u00e0 la justice<\/span><\/a><span style=\"font-weight: 400;\"> lorsque les menaces visent \u00e0 dissuader des t\u00e9moins. La coercition et le chantage peuvent relever de l\u2019article 346.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-3a4e3d0 elementor-widget elementor-widget-heading\" data-id=\"3a4e3d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Peines et d\u00e9termination de la peine pour extorsion<\/h3>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-f7153d6 elementor-widget elementor-widget-text-editor\" data-id=\"f7153d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">L\u2019extorsion est une infraction punissable par mise en accusation qui comporte une peine maximale d\u2019emprisonnement \u00e0 perp\u00e9tuit\u00e9. Contrairement au vol qualifi\u00e9, l\u2019extorsion ne comporte aucune peine minimale obligatoire dans la plupart des circonstances, ce qui donne aux tribunaux une plus grande marge de man\u0153uvre au moment de la d\u00e9termination de la peine. Toutefois, une condamnation entra\u00eene tout de m\u00eame un casier judiciaire permanent et une possible peine d\u2019emprisonnement. Lorsque l\u2019extorsion et le vol qualifi\u00e9 sont port\u00e9s pour la m\u00eame conduite, les cons\u00e9quences li\u00e9es \u00e0 la peine peuvent se cumuler.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-1437d37 elementor-widget elementor-widget-n-accordion\" data-id=\"1437d37\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\"> \t\t\t\t\t\t<details id=\"e-n-accordion-item-2120\" class=\"e-n-accordion-item\" > \t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2120\" > \t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> En savoir plus <\/div><\/span> \t\t\t\t\t\t\t\t\t<\/summary> \t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-2120\" class=\"elementor-element elementor-element-b21a7ec e-con-full e-flex e-con e-child\" data-id=\"b21a7ec\" data-element_type=\"container\" data-e-type=\"container\"> \t\t\t\t<div class=\"elementor-element elementor-element-c82e397 elementor-widget elementor-widget-text-editor\" data-id=\"c82e397\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<h2>Peines pour vol qualifi\u00e9 et extorsion \u00e0 Ottawa<\/h2><p><span style=\"font-weight: 400;\">Les peines pour vol qualifi\u00e9 pr\u00e9vues par le droit canadien, ainsi que celles applicables \u00e0 l\u2019extorsion, vont bien au-del\u00e0 de la sentence elle-m\u00eame :<\/span><\/p><ol><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Peine d\u2019emprisonnement minimale obligatoire pour vol qualifi\u00e9 avec une arme \u00e0 feu, soit un minimum de 4 ans ou de 5 ans avec une organisation criminelle;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Emprisonnement maximal \u00e0 perp\u00e9tuit\u00e9 pour le vol qualifi\u00e9 et l\u2019extorsion;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Casier judiciaire permanent ayant des cons\u00e9quences sur l\u2019emploi dans la plupart des professions r\u00e9glement\u00e9es;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Restrictions de voyage, l\u2019entr\u00e9e aux \u00c9tats-Unis \u00e9tant r\u00e9guli\u00e8rement refus\u00e9e pour des condamnations par mise en accusation;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Cons\u00e9quences en immigration pouvant \u00eatre irr\u00e9versibles pour les non-citoyens;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Ordonnances d\u2019interdiction de possession d\u2019armes;<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Accusations de <\/span><a href=\"https:\/\/frouharlaw.com\/fr\/notre-expertise\/infractions-contre-les-biens\/possession-de-biens-criminellement-obtenus\/\"><span style=\"font-weight: 400;\">possession de biens vol\u00e9s<\/span><\/a><span style=\"font-weight: 400;\"> souvent port\u00e9es avec le vol qualifi\u00e9, ce qui aggrave l\u2019impact sur le casier judiciaire.<\/span><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/details> \t\t\t\t\t<\/div> \t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-f7fbb66 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7fbb66\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"> \t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-38e3387\" data-id=\"38e3387\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-163ab13 elementor-widget elementor-widget-heading\" data-id=\"163ab13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9fenses contre les accusations de vol qualifi\u00e9 et d\u2019extorsion<\/h2>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-d9b3f2a elementor-align-left elementor-widget elementor-widget-button\" data-id=\"d9b3f2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\"> \t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/frouharlaw.com\/fr\/contactez-nous\/\"> \t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\"> \t\t\t\t\t\t<span class=\"elementor-button-icon\"> \t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span> \t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Planifier une consultation<\/span> \t\t\t\t\t<\/span> \t\t\t\t\t<\/a> \t\t\t\t<\/div> \t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-df52070\" data-id=\"df52070\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8da0d2 elementor-widget elementor-widget-text-editor\" data-id=\"d8da0d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La Couronne doit prouver chaque \u00e9l\u00e9ment d\u2019une accusation de vol qualifi\u00e9 ou d\u2019extorsion hors de tout doute raisonnable, et Frouhar Law contestera chacun de ces \u00e9l\u00e9ments d\u00e8s le d\u00e9part. Nos avocats proc\u00e8dent \u00e0 un examen approfondi de la divulgation de la Couronne d\u00e8s le mandat sign\u00e9 et ciblent les points les plus faibles du dossier de la poursuite.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-f8ece00 elementor-widget elementor-widget-n-accordion\" data-id=\"f8ece00\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\"> \t\t\t\t\t\t<details id=\"e-n-accordion-item-2610\" class=\"e-n-accordion-item\" > \t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2610\" > \t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\">  Contester la preuve d\u2019identification <\/h3><\/span> \t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'> \t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span> \t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span> \t\t<\/span>  \t\t\t\t\t\t<\/summary> \t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-2610\" class=\"elementor-element elementor-element-08b5905 e-con-full e-flex e-con e-child\" data-id=\"08b5905\" data-element_type=\"container\" data-e-type=\"container\"> \t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-2610\" class=\"elementor-element elementor-element-4401c3b e-flex e-con-boxed e-con e-child\" data-id=\"4401c3b\" data-element_type=\"container\" data-e-type=\"container\"> \t\t\t\t\t<div class=\"e-con-inner\"> \t\t\t\t<div class=\"elementor-element elementor-element-cb9c78d elementor-widget elementor-widget-text-editor\" data-id=\"cb9c78d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Les dossiers de vol qualifi\u00e9 reposent fr\u00e9quemment sur l\u2019identification: une victime ou un t\u00e9moin oculaire identifie l\u2019accus\u00e9 sous pression, dans un contexte o\u00f9 les erreurs d\u2019identification sont bien document\u00e9es. La d\u00e9fense conteste la proc\u00e9dure d\u2019identification photographique, la fiabilit\u00e9 de la preuve vid\u00e9o et la question de savoir si une preuve d\u2019alibi place l\u2019accus\u00e9 ailleurs.<\/span><\/p><p><span style=\"font-weight: 400;\">Une d\u00e9fense fond\u00e9e sur l\u2019erreur d\u2019identit\u00e9 qui soul\u00e8ve un doute raisonnable m\u00e8ne \u00e0 un acquittement.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/details> \t\t\t\t\t\t<details id=\"e-n-accordion-item-2611\" class=\"e-n-accordion-item\" > \t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2611\" > \t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Contester l\u2019intention et l\u2019utilisation de la force <\/h3><\/span> \t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'> \t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span> \t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span> \t\t<\/span>  \t\t\t\t\t\t<\/summary> \t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-2611\" class=\"elementor-element elementor-element-a16d320 e-con-full e-flex e-con e-child\" data-id=\"a16d320\" data-element_type=\"container\" data-e-type=\"container\"> \t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-2611\" class=\"elementor-element elementor-element-2e5815d e-flex e-con-boxed e-con e-child\" data-id=\"2e5815d\" data-element_type=\"container\" data-e-type=\"container\"> \t\t\t\t\t<div class=\"e-con-inner\"> \t\t\t\t<div class=\"elementor-element elementor-element-4e99e48 elementor-widget elementor-widget-text-editor\" data-id=\"4e99e48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Le vol qualifi\u00e9 exige la preuve que la force ou les menaces ont \u00e9t\u00e9 utilis\u00e9es pr\u00e9cis\u00e9ment en lien avec un vol. Lorsque la Couronne ne peut pas prouver cette intention, l\u2019accusation peut \u00e9chouer. Si la force ne peut pas \u00eatre rattach\u00e9e \u00e0 l\u2019\u00e9l\u00e9ment du vol, l\u2019accusation peut \u00eatre r\u00e9duite \u00e0 des voies de fait, ce qui retire les peines minimales obligatoires et ouvre un \u00e9ventail plus large de r\u00e9sultats.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/details> \t\t\t\t\t\t<details id=\"e-n-accordion-item-2612\" class=\"e-n-accordion-item\" > \t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2612\" > \t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Violations des droits garantis par la Charte et exclusion de la preuve <\/h3><\/span> \t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'> \t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span> \t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span> \t\t<\/span>  \t\t\t\t\t\t<\/summary> \t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-2612\" class=\"elementor-element elementor-element-7702f87 e-con-full e-flex e-con e-child\" data-id=\"7702f87\" data-element_type=\"container\" data-e-type=\"container\"> \t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-2612\" class=\"elementor-element elementor-element-095e8cc e-flex e-con-boxed e-con e-child\" data-id=\"095e8cc\" data-element_type=\"container\" data-e-type=\"container\"> \t\t\t\t\t<div class=\"e-con-inner\"> \t\t\t\t<div class=\"elementor-element elementor-element-fb589f3 elementor-widget elementor-widget-text-editor\" data-id=\"fb589f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Les enqu\u00eates polici\u00e8res en mati\u00e8re de vol qualifi\u00e9 impliquent souvent des fouilles sans mandat ou des interrogatoires qui peuvent constituer une violation de la <\/span><a href=\"https:\/\/www.justice.gc.ca\/fra\/sjc-csj\/dlc-rfc\/ccdl-ccrf\/\"><span style=\"font-weight: 400;\">Charte canadienne des droits et libert\u00e9s<\/span><\/a><span style=\"font-weight: 400;\">. Une <\/span><a href=\"https:\/\/frouharlaw.com\/fr\/notre-expertise\/motions-et-demandes-relatives-a-la-charte\/\"><span style=\"font-weight: 400;\">requ\u00eate fond\u00e9e sur la Charte<\/span><\/a><span style=\"font-weight: 400;\"> peut faire exclure une preuve vici\u00e9e du proc\u00e8s. Le dossier de vol qualifi\u00e9 de la Couronne d\u00e9pend souvent d\u2019un petit nombre d\u2019\u00e9l\u00e9ments cl\u00e9s. En faire exclure un peu tout changer.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/details> \t\t\t\t\t\t<details id=\"e-n-accordion-item-2613\" class=\"e-n-accordion-item\" > \t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2613\" > \t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\">  Strat\u00e9gies de r\u00e9duction des accusations <\/h3><\/span> \t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'> \t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span> \t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span> \t\t<\/span>  \t\t\t\t\t\t<\/summary> \t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-2613\" class=\"elementor-element elementor-element-6c1104f e-con-full e-flex e-con e-child\" data-id=\"6c1104f\" data-element_type=\"container\" data-e-type=\"container\"> \t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" role=\"region\" aria-labelledby=\"e-n-accordion-item-2613\" class=\"elementor-element elementor-element-4341fc4 e-flex e-con-boxed e-con e-child\" data-id=\"4341fc4\" data-element_type=\"container\" data-e-type=\"container\"> \t\t\t\t\t<div class=\"e-con-inner\"> \t\t\t\t<div class=\"elementor-element elementor-element-9d7d098 elementor-widget elementor-widget-text-editor\" data-id=\"9d7d098\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Lorsque la preuve est solide, l\u2019objectif consiste \u00e0 r\u00e9duire les cons\u00e9quences. Dans les dossiers de vol qualifi\u00e9 avec une arme \u00e0 feu, contester la classification de l\u2019arme peut d\u00e9terminer quelle peine minimale obligatoire s\u2019applique. Retirer l\u2019\u00e9l\u00e9ment de l\u2019arme peut permettre de r\u00e9duire une accusation de vol qualifi\u00e9 \u00e0 une accusation de vol, offrant ainsi une beaucoup plus grande flexibilit\u00e9 au moment de la peine.<\/span><\/p><p><span style=\"font-weight: 400;\">La d\u00e9fense peut n\u00e9gocier un plaidoyer, rechercher une d\u00e9judiciarisation ou demander une absolution conditionnelle. Le meilleur r\u00e9sultat possible d\u00e9pend d\u2019une repr\u00e9sentation rapide et exp\u00e9riment\u00e9e ainsi que des faits propres \u00e0 votre dossier.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/details> \t\t\t\t\t<\/div> \t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-fa141f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa141f4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"> \t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div> \t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-601d841\" data-id=\"601d841\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-086ba53 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"086ba53\" data-element_type=\"section\" data-e-type=\"section\"> \t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b36bf7e\" data-id=\"b36bf7e\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap\"> \t\t\t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-36069d1\" data-id=\"36069d1\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-c814149 elementor-widget elementor-widget-heading\" data-id=\"c814149\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Les trois \u00e9tapes vers la r\u00e9ussite<\/h4>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-5cd2dc6 elementor-widget elementor-widget-heading\" data-id=\"5cd2dc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nous vous accompagnerons \u00e0 chaque \u00e9tape<\/h2>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-5c92f86 elementor-widget elementor-widget-text-editor\" data-id=\"5c92f86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Notre mission est de garantir l&rsquo;acc\u00e8s \u00e0 la justice pour tous, quels que soient les revenus ou le statut social, en proposant une repr\u00e9sentation et des conseils juridiques de qualit\u00e9 \u00e0 des tarifs abordables. Notre objectif est de donner aux personnes les moyens de d\u00e9fendre leurs droits et de r\u00e9soudre leurs probl\u00e8mes juridiques de mani\u00e8re efficace et efficiente.<\/p>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1cb9ef3\" data-id=\"1cb9ef3\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap\"> \t\t\t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-58add35 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58add35\" data-element_type=\"section\" data-e-type=\"section\"> \t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5f55515\" data-id=\"5f55515\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c1e935 elementor-widget elementor-widget-heading\" data-id=\"1c1e935\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">01<\/h2>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-53e8414 elementor-widget elementor-widget-heading\" data-id=\"53e8414\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">vous renseigner sur toutes vos questions juridiques<\/h3>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-767d858\" data-id=\"767d858\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e16d7c elementor-widget elementor-widget-heading\" data-id=\"3e16d7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">02<\/h2>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-1d48a34 elementor-widget elementor-widget-heading\" data-id=\"1d48a34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Trouvez l'avocat qui vous convient le mieux<\/h3>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-addbf15\" data-id=\"addbf15\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-cafae08 elementor-widget elementor-widget-heading\" data-id=\"cafae08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">03<\/h2>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-a966ad3 elementor-widget elementor-widget-heading\" data-id=\"a966ad3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Je vous d\u00e9fendrai devant le tribunal.<\/h3>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<div class=\"elementor-element elementor-element-1aa2978 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1aa2978\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\"> \t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/frouharlaw.com\/fr\/contact\/\"> \t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\"> \t\t\t\t\t\t<span class=\"elementor-button-icon\"> \t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span> \t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Planifier une consultation<\/span> \t\t\t\t\t<\/span> \t\t\t\t\t<\/a> \t\t\t\t<\/div> \t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-710d275 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"710d275\" data-element_type=\"section\" data-e-type=\"section\"> \t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ad56dd\" data-id=\"3ad56dd\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-aae447c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aae447c\" data-element_type=\"section\" data-e-type=\"section\"> \t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8f8c983\" data-id=\"8f8c983\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-6334b30 elementor-widget elementor-widget-heading\" data-id=\"6334b30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Ce que les gens disent de nous<\/span>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-c38463d elementor-widget elementor-widget-heading\" data-id=\"c38463d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T\u00e9moignages clients<\/h2>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-83c8604\" data-id=\"83c8604\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-41f5ad0 elementor-testimonial--layout-image_left elementor-testimonial--align-left elementor-testimonial--skin-default elementor-arrows-yes elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"41f5ad0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;autoplay_speed&quot;:&quot;3500&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;slides_per_view_tablet&quot;:&quot;1&quot;,&quot;slides_per_view_mobile&quot;:&quot;1&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\"> \t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\"> \t\t\t\t<div class=\"swiper-wrapper\"> \t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\"> \t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\"> \t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\"> \t\t\t\t\t<div class=\"elementor-testimonial__text\"> \t\t\t\t\t\tA few years ago I observed Mrs Mash Frouhar in action during a court trial.  I was so impressed at how brilliant she is.  I approached her for a business card just in case I needed a very good lawyer in the future.  A few years later she got me out on bail.  My trial was delayed almost  2 years because of covid-19. I was found innocent on all charges.  Mrs. Mash Frouhar, Mr. Matthew Yassa and team, I trust you with my life. I love how they dealt with my case, they're real professionals.  A million thanks for winning, you all are the best\t\t\t\t\t<\/div> \t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Keith Smith<\/span><\/cite>\t\t\t\t<\/div> \t\t\t\t\t\t<div class=\"elementor-testimonial__footer\"> \t\t\t\t\t\t\t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t\t\t\t<\/div> \t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\"> \t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\"> \t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\"> \t\t\t\t\t<div class=\"elementor-testimonial__text\"> \t\t\t\t\t\tConnie D\u2019Angelo of Frouhar Law did outstanding work counselling and representing me for my case. I couldn\u2019t have found a better lawyer and firm. From the initial meeting all the way through to the final trial date Connie represented nothing but the highest degree professionalism. The judge acknowledged the incredible work that she presented for my case and couldn\u2019t have helped me better. Forever grateful for Connie D\u2019Angelo\u2019s professionalism with my case.\t\t\t\t\t<\/div> \t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">Vicente Ramos<\/span><\/cite>\t\t\t\t<\/div> \t\t\t\t\t\t<div class=\"elementor-testimonial__footer\"> \t\t\t\t\t\t\t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t\t\t\t<\/div> \t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\"> \t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\"> \t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\"> \t\t\t\t\t<div class=\"elementor-testimonial__text\"> \t\t\t\t\t\tThis firm will fight tooth and nail for you. Mash is the best lawyer I have ever met, she will guide threw all your options and help you pick the best one, they are always available and the receptionist always picks up the phone for you at any time and gives an amazing service and follow up. I was amazed by Frouhar Law and their team in both English and French!!!\t\t\t\t\t<\/div> \t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">david maltais<\/span><\/cite>\t\t\t\t<\/div> \t\t\t\t\t\t<div class=\"elementor-testimonial__footer\"> \t\t\t\t\t\t\t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t\t\t\t<\/div> \t\t\t\t\t\t\t\t\t<\/div> \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00e9c\u00e9dent\"> \t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div> \t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Suivant\"> \t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div> \t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div> \t\t\t\t\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<div class=\"elementor-element elementor-element-3a6c52f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3a6c52f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\"> \t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.google.com\/search?q=frouharlaw+google#038&oq=frouharlaw+google&#038&aqs=chrome..69i57j69i60.3680j0j7&#038&sourceid=chrome&#038&ie=UTF-8#lrd=0x4cce0455166e1c0d:0x9e8eb7653e2cfb2e,1,,,,\" target=\"_blank\"> \t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\"> \t\t\t\t\t\t<span class=\"elementor-button-icon\"> \t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span> \t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir tout sur Google<\/span> \t\t\t\t\t<\/span> \t\t\t\t\t<\/a> \t\t\t\t<\/div> \t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-02033e5 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"02033e5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"> \t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div> \t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0274b1d\" data-id=\"0274b1d\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9f3d2b elementor-widget elementor-widget-heading\" data-id=\"a9f3d2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Prendre rendez-vous pour une consultation <\/h3>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-270b230 elementor-widget elementor-widget-text-editor\" data-id=\"270b230\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<h4><span style=\"font-weight: 400;\">Plus vous retenez t\u00f4t les services d\u2019un avocat de la d\u00e9fense, plus les options demeurent ouvertes.<\/span><\/h4>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-81763e0 elementor-widget elementor-widget-heading\" data-id=\"81763e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\t\u2706 613.238.2000<\/h5>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-c15dfe7 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c15dfe7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\"> \t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/frouharlaw.com\/fr\/contactez-nous\/\"> \t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\"> \t\t\t\t\t\t<span class=\"elementor-button-icon\"> \t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span> \t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez Frouhar Law d\u00e8s aujourd'hui<\/span> \t\t\t\t\t<\/span> \t\t\t\t\t<\/a> \t\t\t\t<\/div> \t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-babc022 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"babc022\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\"> \t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\"> \t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5950c8f\" data-id=\"5950c8f\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-4de56b5 elementor-widget elementor-widget-heading\" data-id=\"4de56b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">FAQs<\/span>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t<div class=\"elementor-element elementor-element-e3dff5d elementor-widget elementor-widget-heading\" data-id=\"e3dff5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">En savoir plus sur les vols qualifi\u00e9s en Ontario <\/h2>\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-63c2e21\" data-id=\"63c2e21\" data-element_type=\"column\" data-e-type=\"column\"> \t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\"> \t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d61be7 elementor-widget elementor-widget-text-editor\" data-id=\"3d61be7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\"> \t\t\t\t<div class=\"elementor-widget-container\"> \t\t\t\t\t\t\t\t\t<h4>Le vol qualifi\u00e9 est-il toujours une infraction punissable par mise en accusation au Canada?<\/h4><p>Oui. Le vol qualifi\u00e9 pr\u00e9vu \u00e0 l\u2019article 343 du Code criminel est une infraction strictement punissable par mise en accusation. La Couronne ne peut pas proc\u00e9der par voie sommaire. Le dossier est entendu devant la Cour de justice de l\u2019Ontario ou la Cour sup\u00e9rieure de justice, et les peines font partie des plus graves en droit criminel canadien.<\/p><h4>Quelle est la diff\u00e9rence entre le vol qualifi\u00e9 et l\u2019extorsion?<\/h4><p>Le vol qualifi\u00e9 pr\u00e9vu \u00e0 l\u2019article 343 du Code criminel exige que la force ou les menaces soient utilis\u00e9es pendant un vol. Le vol et la violence sont donc li\u00e9s. L\u2019extorsion pr\u00e9vue \u00e0 l\u2019article 346 du Code criminel est plus large: des menaces servent \u00e0 contraindre une personne \u00e0 accomplir une action, pas seulement \u00e0 remettre un bien, et la menace peut viser un pr\u00e9judice futur. Une demande d\u2019argent appuy\u00e9e par une menace future rel\u00e8ve de l\u2019extorsion. La prise de biens par force imm\u00e9diate rel\u00e8ve du vol qualifi\u00e9.<\/p><h4>Les accusations de vol qualifi\u00e9 ou d\u2019extorsion peuvent-elles \u00eatre retir\u00e9es \u00e0 Ottawa?<\/h4><p>Oui. Les accusations de vol qualifi\u00e9 et d\u2019extorsion \u00e0 Ottawa peuvent \u00eatre retir\u00e9es, suspendues ou mener \u00e0 un acquittement. Lorsque la preuve est insuffisante, les procureurs de la Couronne ont le pouvoir discr\u00e9tionnaire de retirer les accusations avant le proc\u00e8s. Une d\u00e9fense qui pr\u00e9sente des \u00e9l\u00e9ments minant l\u2019identification, l\u2019intention ou l\u2019utilisation de la force peut mener au retrait des accusations ou \u00e0 leur r\u00e9duction \u00e0 une infraction moindre. <a href=\"https:\/\/frouharlaw.com\/fr\/contactez-nous\/\">Planifiez une consultation gratuite<\/a> pour discuter de votre situation.<\/p>\t\t\t\t\t\t\t\t<\/div> \t\t\t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/div> \t\t\t\t\t<\/div> \t\t<\/section> \t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Avocat pour vol qualifi\u00e9 \u00e0 Ottawa Soutien juridique complet pour les dossiers de vol qualifi\u00e9 et d\u2019extorsion Frouhar Law d\u00e9fend les accusations de vol qualifi\u00e9 que les procureurs de la Couronne portent devant le palais de justice d\u2019Ottawa et partout dans l\u2019Est de l\u2019Ontario. Ces accusations peuvent entra\u00eener des peines minimales obligatoires, une peine maximale [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":183,"menu_order":35,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2308","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avocat pour vol qualifi\u00e9 Ottawa | Frouhar Law<\/title>\n<meta name=\"description\" content=\"Accus\u00e9 de vol qualifi\u00e9 ou d\u2019extorsion \u00e0 Ottawa? Les avocats criminalistes de Frouhar Law d\u00e9fendent ces accusations. Ancienne procureure de la Couronne. Bilingue. Consultation gratuite: 613.238.2000.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avocat pour vol qualifi\u00e9 Ottawa | Frouhar Law\" \/>\n<meta property=\"og:description\" content=\"Accus\u00e9 de vol qualifi\u00e9 ou d\u2019extorsion \u00e0 Ottawa? Les avocats criminalistes de Frouhar Law d\u00e9fendent ces accusations. Ancienne procureure de la Couronne. Bilingue. Consultation gratuite: 613.238.2000.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/\" \/>\n<meta property=\"og:site_name\" content=\"Frouhar Law\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T15:11:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/frouharlaw.com\/wp-content\/uploads\/frouharlaw-og.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/\",\"url\":\"https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/\",\"name\":\"Avocat pour vol qualifi\u00e9 Ottawa | Frouhar Law\",\"isPartOf\":{\"@id\":\"https:\/\/frouharlaw.com\/#website\"},\"datePublished\":\"2023-02-09T20:13:54+00:00\",\"dateModified\":\"2026-05-26T15:11:47+00:00\",\"description\":\"Accus\u00e9 de vol qualifi\u00e9 ou d\u2019extorsion \u00e0 Ottawa? Les avocats criminalistes de Frouhar Law d\u00e9fendent ces accusations. Ancienne procureure de la Couronne. Bilingue. Consultation gratuite: 613.238.2000.\",\"breadcrumb\":{\"@id\":\"https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/frouharlaw.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comp\u00e9tences\",\"item\":\"https:\/\/frouharlaw.com\/fr\/notre-expertise\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Avocat pour vol qualifi\u00e9 \u00e0 Ottawa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/frouharlaw.com\/#website\",\"url\":\"https:\/\/frouharlaw.com\/\",\"name\":\"Frouhar Law\",\"description\":\"Determined. Creative. Tireless. Passionate.\",\"publisher\":{\"@id\":\"https:\/\/frouharlaw.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/frouharlaw.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/frouharlaw.com\/#organization\",\"name\":\"Frouhar Law\",\"url\":\"https:\/\/frouharlaw.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/frouharlaw.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/frouharlaw.com\/wp-content\/uploads\/frouhar-law-logo.png\",\"contentUrl\":\"https:\/\/frouharlaw.com\/wp-content\/uploads\/frouhar-law-logo.png\",\"width\":3601,\"height\":3600,\"caption\":\"Frouhar Law\"},\"image\":{\"@id\":\"https:\/\/frouharlaw.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avocat pour vol qualifi\u00e9 Ottawa | Frouhar Law","description":"Accus\u00e9 de vol qualifi\u00e9 ou d\u2019extorsion \u00e0 Ottawa? Les avocats criminalistes de Frouhar Law d\u00e9fendent ces accusations. Ancienne procureure de la Couronne. Bilingue. Consultation gratuite: 613.238.2000.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/","og_locale":"fr_FR","og_type":"article","og_title":"Avocat pour vol qualifi\u00e9 Ottawa | Frouhar Law","og_description":"Accus\u00e9 de vol qualifi\u00e9 ou d\u2019extorsion \u00e0 Ottawa? Les avocats criminalistes de Frouhar Law d\u00e9fendent ces accusations. Ancienne procureure de la Couronne. Bilingue. Consultation gratuite: 613.238.2000.","og_url":"https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/","og_site_name":"Frouhar Law","article_modified_time":"2026-05-26T15:11:47+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/frouharlaw.com\/wp-content\/uploads\/frouharlaw-og.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/","url":"https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/","name":"Avocat pour vol qualifi\u00e9 Ottawa | Frouhar Law","isPartOf":{"@id":"https:\/\/frouharlaw.com\/#website"},"datePublished":"2023-02-09T20:13:54+00:00","dateModified":"2026-05-26T15:11:47+00:00","description":"Accus\u00e9 de vol qualifi\u00e9 ou d\u2019extorsion \u00e0 Ottawa? Les avocats criminalistes de Frouhar Law d\u00e9fendent ces accusations. Ancienne procureure de la Couronne. Bilingue. Consultation gratuite: 613.238.2000.","breadcrumb":{"@id":"https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/frouharlaw.com\/fr\/notre-expertise\/vol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/frouharlaw.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Comp\u00e9tences","item":"https:\/\/frouharlaw.com\/fr\/notre-expertise\/"},{"@type":"ListItem","position":3,"name":"Avocat pour vol qualifi\u00e9 \u00e0 Ottawa"}]},{"@type":"WebSite","@id":"https:\/\/frouharlaw.com\/#website","url":"https:\/\/frouharlaw.com\/","name":"Frouhar Law","description":"Determined. Creative. Tireless. Passionate.","publisher":{"@id":"https:\/\/frouharlaw.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/frouharlaw.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/frouharlaw.com\/#organization","name":"Frouhar Law","url":"https:\/\/frouharlaw.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/frouharlaw.com\/#\/schema\/logo\/image\/","url":"https:\/\/frouharlaw.com\/wp-content\/uploads\/frouhar-law-logo.png","contentUrl":"https:\/\/frouharlaw.com\/wp-content\/uploads\/frouhar-law-logo.png","width":3601,"height":3600,"caption":"Frouhar Law"},"image":{"@id":"https:\/\/frouharlaw.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/frouharlaw.com\/fr\/wp-json\/wp\/v2\/pages\/2308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/frouharlaw.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/frouharlaw.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/frouharlaw.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/frouharlaw.com\/fr\/wp-json\/wp\/v2\/comments?post=2308"}],"version-history":[{"count":23,"href":"https:\/\/frouharlaw.com\/fr\/wp-json\/wp\/v2\/pages\/2308\/revisions"}],"predecessor-version":[{"id":4723,"href":"https:\/\/frouharlaw.com\/fr\/wp-json\/wp\/v2\/pages\/2308\/revisions\/4723"}],"up":[{"embeddable":true,"href":"https:\/\/frouharlaw.com\/fr\/wp-json\/wp\/v2\/pages\/183"}],"wp:attachment":[{"href":"https:\/\/frouharlaw.com\/fr\/wp-json\/wp\/v2\/media?parent=2308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}